{"id":1494,"date":"2017-09-01T03:24:58","date_gmt":"2017-09-01T03:24:58","guid":{"rendered":"http:\/\/www.cafesaula.com\/blog\/?p=1494"},"modified":"2017-09-01T06:57:43","modified_gmt":"2017-09-01T06:57:43","slug":"3-curiositats-sobre-el-mon-del-cafe","status":"publish","type":"post","link":"https:\/\/www.cafesaula.com\/blog\/3-curiositats-sobre-el-mon-del-cafe\/","title":{"rendered":"3 curiosidades sobre el mundo del caf\u00e9"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">La <strong>historia del caf\u00e9<\/strong> nos ha dejado un gran n\u00famero de historias y curiosidades que no hacen sino enriquecer todav\u00eda m\u00e1s su leyenda. Des de <strong><a href=\"http:\/\/www.cafesaula.com\/es\/\">Caf\u00e9 Saula<\/a><\/strong> os explicamos algunas:<\/p>\n<p><strong>1. En Europa el caf\u00e9 era conocido como \u201cvino \u00e1rabe\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Es posible que no sepas que cuando <strong>el caf\u00e9 lleg\u00f3 por primera vez en Europa<\/strong>, durante el <strong>siglo XVII,<\/strong> era popularmente conocido como <strong>\u201cvino \u00e1rabe\u201d<\/strong>. De hecho, la palabra caf\u00e9 proviene de la <strong>palabra \u00e1rabe \u201cqahhwat al-bun\u201d<\/strong>, que se traduce como <strong>vino de grano<\/strong>. M\u00e1s tarde la palabra deriv\u00f3 a <strong>\u201cqahhwat\u201d<\/strong>, que en <strong>Turqu\u00eda <\/strong>pas\u00f3 a decirse <strong>\u201ckahveh\u201d<\/strong>, <strong>\u201ckoffie\u201d<\/strong> en <strong>Holanda<\/strong> y finalmente <strong>\u201ccaffe\u201d en Italia<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong> 2. La cafeter\u00eda m\u00e1s antigua de Europa es el Caf\u00e9 Florian en Venecia<\/strong><\/p>\n<p style=\"text-align: justify;\">El famoso <strong><a href=\"https:\/\/www.caffeflorian.com\/en\/\">Caf\u00e9 Florian<\/a> de Venecia<\/strong> tiene fama de ser la <strong>cafeter\u00eda m\u00e1s antigua de Europa<\/strong>. Abri\u00f3 sus puertas en <strong>1720<\/strong> en la c\u00e9ntrica <strong>Plaza San Marcos<\/strong> con el nombre de <strong>\u2018Alla Venezia Trionfante\u2019<\/strong>. Desde entonces, ha sido el lugar de recogimiento de ilustres personajes como <strong>Vivaldi, Proust o Dickens<\/strong>.<\/p>\n<p><strong>3. Finlandia es el pa\u00eds que m\u00e1s consume caf\u00e9<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ni Italia ni Colombia<\/strong>. El pa\u00eds donde se registra un <strong>consumo de caf\u00e9 m\u00e1s alto de todo el mundo es Finlandia<\/strong>. Es posible que sea como consecuencia de su <strong>clima tan fr\u00edo y hostil<\/strong>. En todo caso, se calcula que la <strong>media de consumo de caf\u00e9<\/strong> de un habitante a lo largo del a\u00f1o es de <strong>12 kg<\/strong>, que equivaldr\u00eda a unas <strong>1.200 tazas de caf\u00e9 por persona<\/strong>.<\/p>\n<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La historia del caf\u00e9 nos ha dejado un gran n\u00famero de historias y curiosidades que no hacen sino enriquecer todav\u00eda m\u00e1s su leyenda. Des de Caf\u00e9 Saula os explicamos algunas: 1. En Europa el caf\u00e9 era conocido como \u201cvino \u00e1rabe\u201d Es posible que no sepas que cuando el caf\u00e9 lleg\u00f3 por primera vez en Europa,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1495,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,2,49,164],"tags":[35,487,50,696,296,695,297,693,694,488,692],"class_list":["post-1494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafeterias","category-cafe","category-historia","category-ritualers-2","tag-cafe-2","tag-cafe-florian","tag-cafe-saula","tag-consumo-cafe","tag-curiosidades","tag-finlandia","tag-historia-2","tag-historia-del-cafe","tag-italia","tag-venecia","tag-vino-arabe"],"_links":{"self":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/1494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/comments?post=1494"}],"version-history":[{"count":10,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/1494\/revisions"}],"predecessor-version":[{"id":1558,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/1494\/revisions\/1558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media\/1495"}],"wp:attachment":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media?parent=1494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/categories?post=1494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/tags?post=1494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}