{"id":1988,"date":"2019-01-17T08:19:26","date_gmt":"2019-01-17T08:19:26","guid":{"rendered":"http:\/\/www.cafesaula.com\/blog\/?p=1988"},"modified":"2019-01-17T08:19:26","modified_gmt":"2019-01-17T08:19:26","slug":"raco-den-cesc-cafe-de-qualitat-al-centre-de-barcelona","status":"publish","type":"post","link":"https:\/\/www.cafesaula.com\/blog\/raco-den-cesc-cafe-de-qualitat-al-centre-de-barcelona\/","title":{"rendered":"Rac\u00f3 d\u2019en Cesc, caf\u00e9 de calidad en el centro de Barcelona"},"content":{"rendered":"<p>Considerado como uno de los restaurantes de referencia de Barcelona, desde 1986 se encuentra en pleno centro de la ciudad el <a href=\"http:\/\/www.elracodencesc.com\/\"><strong>Rac\u00f3 d\u2019en Cesc<\/strong><\/a>. Un acogedor local con estrella Michelin que hace las delicias de quienes buscan el perfecto maridaje de la cocina catalana actualizada con las mejores referencias en vinos y cervezas.<\/p>\n<p>Y como no pod\u00eda ser de otro modo, desde hace tiempo la fam\u00edlia Canovas apuesta por servir <a href=\"http:\/\/www.cafesaula.com\/store\/es\/cafe-molido\/1-gran-espresso-premium-natural\"><strong>Caf\u00e9 Saula Premium Original<\/strong><\/a>, como una manera de redondear una comida o cena para los m\u00e1s sibaritas.<\/p>\n<p>Todo ello se convierte en una experiencia gastron\u00f3mica en un espacio caracterizado por varios rincones que destacan por su recogimiento y una \u00edntima decoraci\u00f3n. En definitiva, un ambiente c\u00e1lido con que los propietarios quieren ofrecer en todo momento una atenci\u00f3n personalizada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Considerado como uno de los restaurantes de referencia de Barcelona, desde 1986 se encuentra en pleno centro de la ciudad el Rac\u00f3 d\u2019en Cesc. Un acogedor local con estrella Michelin que hace las delicias de quienes buscan el perfecto maridaje de la cocina catalana actualizada con las mejores referencias en vinos y cervezas. Y como&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,164],"tags":[35,50,271,915],"class_list":["post-1988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafeterias","category-ritualers-2","tag-cafe-2","tag-cafe-saula","tag-premium-original","tag-raco-den-cesc"],"_links":{"self":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/1988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/comments?post=1988"}],"version-history":[{"count":2,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/1988\/revisions"}],"predecessor-version":[{"id":1991,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/1988\/revisions\/1991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media\/1990"}],"wp:attachment":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media?parent=1988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/categories?post=1988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/tags?post=1988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}