{"id":2154,"date":"2019-11-13T09:39:16","date_gmt":"2019-11-13T09:39:16","guid":{"rendered":"https:\/\/www.cafesaula.com\/blog\/?p=2154"},"modified":"2019-11-13T09:39:16","modified_gmt":"2019-11-13T09:39:16","slug":"recepta-de-galetes-de-cafe","status":"publish","type":"post","link":"https:\/\/www.cafesaula.com\/blog\/recepta-de-galetes-de-cafe\/","title":{"rendered":"Receta de galletas de caf\u00e9"},"content":{"rendered":"<p>\u00bfTe gustan las galletas y te gusta el caf\u00e9? Si la respuesta es afirmativa, entonces tenemos la receta ideal para ti: <strong>galletas con sabor a caf\u00e9<\/strong>. Se trata de un dulce ideal para servir despu\u00e9s del postre y acompa\u00f1arlo junto con una taza de <strong>Caf\u00e9 Saula<\/strong> para intensificar, a\u00fan m\u00e1s, todo su sabor. La receta es muy f\u00e1cil y puede gustar tanto a grandes como peque\u00f1os. Aqu\u00ed os dejamos una receta con la que pueden salir muchas galletas de tama\u00f1o peque\u00f1o:<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>40 gramos de <strong>Caf\u00e9 Saula molido<\/strong> (<strong>Original, Bourbon o Ecol\u00f3gico<\/strong>)<\/li>\n<li>200 gramos de almendra molida<\/li>\n<li>120 gramos de az\u00facar<\/li>\n<li>160 gramos de mantequilla<\/li>\n<li>2 gramos de escamas de sal<\/li>\n<li>2 huevos<\/li>\n<li>Una pizca de canela<\/li>\n<\/ul>\n<p><strong>Elaboraci\u00f3n:<\/strong><\/p>\n<p>El proceso es muy sencillo: hay que poner todos los ingredientes en el vaso batidor o Thermomix a potencia media, empezando por la mantequilla, que tiene que estar a temperatura ambiente, seguido de la almendra, la harina, el az\u00facar, el caf\u00e9, la canela, la sal y los huevos.<\/p>\n<p>Tras mezclar todos estos ingredientes, quedar\u00e1 una masa homog\u00e9nea y poco consistente. Habr\u00e1 que cubrirla con film transparente y d\u00e9jala reposar en el frigor\u00edfico unas dos horas. Pasado este tiempo, hay que precalentar el horno a 160\u00ba y preparar las bandejas cubri\u00e9ndolas con l\u00e1minas de tefl\u00f3n, silpat o alg\u00fan producto similar.<\/p>\n<p>Una vez se retire la masa de las galletas del frigor\u00edfico, hay que ir haciendo porciones peque\u00f1as con una cucharilla o con la manga pastelera, sin importar su forma, ya que en el horno se expandir\u00e1n, por lo que tambi\u00e9n es importante dejar un poco de espacio entre ellas para que no se peguen.<\/p>\n<p>Seguidamente, hay que hornear las galletas de caf\u00e9 entre 5 y 8 minutos, dependiendo de su tama\u00f1o. Una vez se retiren del horno, a\u00fan estar\u00e1n un poco blandas, pero cuando se enfr\u00eden quedar\u00e1n crujientes. En caso contrario, es que les ha faltado unos minutos de cocci\u00f3n.<\/p>\n<p><strong>Y si todos ha salido bien\u2026 \u00a1ya est\u00e1n listas para servir!<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfTe gustan las galletas y te gusta el caf\u00e9? Si la respuesta es afirmativa, entonces tenemos la receta ideal para ti: galletas con sabor a caf\u00e9. Se trata de un dulce ideal para servir despu\u00e9s del postre y acompa\u00f1arlo junto con una taza de Caf\u00e9 Saula para intensificar, a\u00fan m\u00e1s, todo su sabor. La receta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,164],"tags":[35,966,532,227],"class_list":["post-2154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos","category-ritualers-2","tag-cafe-2","tag-galletas","tag-postres","tag-receta"],"_links":{"self":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/2154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/comments?post=2154"}],"version-history":[{"count":2,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/2154\/revisions"}],"predecessor-version":[{"id":2157,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/2154\/revisions\/2157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media\/2155"}],"wp:attachment":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media?parent=2154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/categories?post=2154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/tags?post=2154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}