{"id":2893,"date":"2022-11-24T07:37:10","date_gmt":"2022-11-24T07:37:10","guid":{"rendered":"https:\/\/www.cafesaula.com\/blog\/?p=2893"},"modified":"2022-11-24T07:44:55","modified_gmt":"2022-11-24T07:44:55","slug":"descubre-el-nuevo-premium-original-con-canela-de-ceylan","status":"publish","type":"post","link":"https:\/\/www.cafesaula.com\/blog\/descubre-el-nuevo-premium-original-con-canela-de-ceylan\/","title":{"rendered":"Descubre el nuevo Premium Original con canela de Ceyl\u00e1n"},"content":{"rendered":"<p>En <strong>Caf\u00e9 Saula<\/strong> acabamos de lanzar en exclusiva\u00a0el <strong>Gran Espresso Premium Original &amp; Fine Cinnamon molido<\/strong>, que ya se ha convertido en uno de nuestros blends m\u00e1s selectos. Se vende en una lata de 250 gramos de una meticulosa selecci\u00f3n de caf\u00e9 ar\u00e1bica molido con aproximadamente un 10% de<strong> canela de Ceyl\u00e1n<\/strong>, tambi\u00e9n molida.<\/p>\n<p>A trav\u00e9s de un selecto proceso artesanal, en <strong>Caf\u00e9 Saula<\/strong> molemos la canela en rama y la mezclamos en su justa medida con el Premium Original 100% ar\u00e1bica. El resultado es una experiencia dulce, especiada y arom\u00e1tica\u00a0de gran calidad. Un maridaje \u00fanico y sorprendente que resulta ideal para un caf\u00e9 largo y fragante.<\/p>\n<p>Originaria de las Indias meridionales, la variedad <strong>Cinnamomun Verum<\/strong> de Sri Lanka, antigua Ceyl\u00e1n, es considerada una de las variedades m\u00e1s finas y apreciadas del mundo por sus grandes cualidades organol\u00e9pticas. Una riqueza arom\u00e1tica que ahora se mezcla con un blend exclusivo. La combinaci\u00f3n perfecta.<\/p>\n<p>Este caf\u00e9 Premium, que est\u00e1 conservado en un <strong>envase met\u00e1lico 100% reciclable<\/strong> cerrado al vac\u00edo con gas inerte para preservar todos los aromas, se puede preparar con la cafetera Moka, el French Press o el caf\u00e9 de filtro.<\/p>\n<p>Descubre m\u00e1s en nuestra tienda online.<\/p>","protected":false},"excerpt":{"rendered":"<p>En Caf\u00e9 Saula acabamos de lanzar en exclusiva\u00a0el Gran Espresso Premium Original &amp; Fine Cinnamon molido, que ya se ha convertido en uno de nuestros blends m\u00e1s selectos. Se vende en una lata de 250 gramos de una meticulosa selecci\u00f3n de caf\u00e9 ar\u00e1bica molido con aproximadamente un 10% de canela de Ceyl\u00e1n, tambi\u00e9n molida. A&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[365],"tags":[1074,1075],"class_list":["post-2893","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-novetats","tag-cafe-con-canela","tag-cafe-saula-premium","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/2893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/comments?post=2893"}],"version-history":[{"count":2,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/2893\/revisions"}],"predecessor-version":[{"id":2896,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/posts\/2893\/revisions\/2896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media\/2897"}],"wp:attachment":[{"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/media?parent=2893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/categories?post=2893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafesaula.com\/blog\/wp-json\/wp\/v2\/tags?post=2893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}